{"id":59,"count":0,"description":"Apportez du style et du caract\u00e8re \u00e0 votre int\u00e9rieur gr\u00e2ce \u00e0 notre s\u00e9lection de d\u00e9coration et accessoires. Miroirs, luminaires, tapis, cadres, horloges et objets d\u00e9coratifs ont \u00e9t\u00e9 soigneusement choisis pour cr\u00e9er des espaces \u00e9l\u00e9gants, chaleureux et modernes. Que vous souhaitiez une ambiance contemporaine, chic ou classique, nos articles de d\u00e9coration vous permettent de personnaliser chaque pi\u00e8ce avec go\u00fbt et raffinement.","link":"https:\/\/cnumeric.net\/tbi\/categorie-produit\/decoration-et-accessoires\/","name":"D\u00e9coration et accessoires","slug":"decoration-et-accessoires","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/cnumeric.net\/tbi\/wp-json\/wp\/v2\/product_cat\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnumeric.net\/tbi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cnumeric.net\/tbi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/cnumeric.net\/tbi\/wp-json\/wp\/v2\/product?product_cat=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}